{
    "id": 623,
    "date": "2022-02-23T19:27:57",
    "date_gmt": "2022-02-24T01:27:57",
    "guid": {
        "rendered": "http:\/\/sweethomelearning.com\/?post_type=product&#038;p=623"
    },
    "modified": "2023-08-29T11:12:34",
    "modified_gmt": "2023-08-29T16:12:34",
    "slug": "sonido-inicial-en-la-granja",
    "status": "publish",
    "type": "product",
    "link": "https:\/\/sweethomelearning.com\/en\/product\/sonido-inicial-en-la-granja\/",
    "title": {
        "rendered": "Sonido Inicial: En la Granja"
    },
    "content": {
        "rendered": "<p>Una manera divertida de aprender o reforzar mientras se trabaja en la identificaci\u00f3n los sonidos iniciales. El ni\u00f1o debe decir el nombre de la imagen y elegir la letra con la que comienza la imagen. Pueden identificar o elegir la letra usando pinzas para la ropa, rodeando la letra correcta con marcadores de borrado en seco, etc.<\/p>\n<p>\u00a1Esta actividad de la granja hace que aprender los sonidos de las letras sea una experiencia divertida!<\/p>\n<p><strong>Incluye:<\/strong><\/p>\n<ul>\n<li><strong><em>28 tarjetas de sonido inicial<\/em><\/strong>\u00a0(todas las im\u00e1genes relacionadas a la granja)<\/li>\n<li><strong><em>7 p\u00e1ginas tama\u00f1o carta<\/em><\/strong>; 4 tarjetas por p\u00e1gina.<\/li>\n<li><em><strong>Im\u00e1genes de acuarela, realistas y amigables con Montessori.<\/strong><\/em><\/li>\n<\/ul>\n<p><em>\u00a1Son f\u00e1ciles de preparar y puede utilizarlas durante muchos a\u00f1os!<\/em><\/p>\n<p>______________________________________________________________________________________________________________<\/p>\n<p><strong>T\u00e9rminos de uso:<\/strong><\/p>\n<p>Todos los derechos reservados. Este material est\u00e1 protegido por derechos de autor. Esta compra da licencia para usarlo \u00fanicamente en su sal\u00f3n de clase o de uso familiar; compartirlo en otro sitio de internet o persona est\u00e1 prohibido. Gracias por respetar mi trabajo.<\/p>\n<p>\u27bc S\u00edguenos en\u00a0<a href=\"https:\/\/www.instagram.com\/sweethomelearning\/\" rel=\"nofollow noopener\">Instagram<\/a>.<\/p>",
        "protected": false
    },
    "excerpt": {
        "rendered": "<p>Una manera divertida de aprender o reforzar mientras se trabaja en la identificaci\u00f3n los sonidos iniciales. El ni\u00f1o debe decir el nombre de la imagen y elegir la letra con la que comienza la imagen. Pueden identificar o elegir la letra usando pinzas para la ropa, rodeando la letra correcta con marcadores de borrado en seco, etc.<\/p>",
        "protected": false
    },
    "featured_media": 520,
    "template": "",
    "meta": [],
    "product_brand": [],
    "product_cat": [
        69,
        71,
        70
    ],
    "product_tag": [],
    "class_list": {
        "0": "post-623",
        "1": "product",
        "2": "type-product",
        "3": "status-publish",
        "4": "has-post-thumbnail",
        "6": "product_cat-ciencias",
        "7": "product_cat-flashcards",
        "8": "product_cat-lenguaje",
        "10": "first",
        "11": "instock",
        "12": "downloadable",
        "13": "taxable",
        "14": "shipping-taxable",
        "15": "purchasable",
        "16": "product-type-simple"
    },
    "_links": {
        "self": [
            {
                "href": "https:\/\/sweethomelearning.com\/en\/wp-json\/wp\/v2\/product\/623",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/sweethomelearning.com\/en\/wp-json\/wp\/v2\/product"
            }
        ],
        "about": [
            {
                "href": "https:\/\/sweethomelearning.com\/en\/wp-json\/wp\/v2\/types\/product"
            }
        ],
        "wp:featuredmedia": [
            {
                "embeddable": true,
                "href": "https:\/\/sweethomelearning.com\/en\/wp-json\/wp\/v2\/media\/520"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/sweethomelearning.com\/en\/wp-json\/wp\/v2\/media?parent=623"
            }
        ],
        "wp:term": [
            {
                "taxonomy": "product_brand",
                "embeddable": true,
                "href": "https:\/\/sweethomelearning.com\/en\/wp-json\/wp\/v2\/product_brand?post=623"
            },
            {
                "taxonomy": "product_cat",
                "embeddable": true,
                "href": "https:\/\/sweethomelearning.com\/en\/wp-json\/wp\/v2\/product_cat?post=623"
            },
            {
                "taxonomy": "product_tag",
                "embeddable": true,
                "href": "https:\/\/sweethomelearning.com\/en\/wp-json\/wp\/v2\/product_tag?post=623"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}